{"id":10301,"date":"2017-11-29T08:31:01","date_gmt":"2017-11-29T13:31:01","guid":{"rendered":"http:\/\/futbolhoy.co\/?p=10301"},"modified":"2017-11-29T12:10:17","modified_gmt":"2017-11-29T17:10:17","slug":"independiente-de-argentina-primer-semifinalista-en-copa-suramericana","status":"publish","type":"post","link":"https:\/\/futbolhoy.co\/index.php\/2017\/11\/29\/independiente-de-argentina-primer-semifinalista-en-copa-suramericana\/","title":{"rendered":"Independiente de Argentina, primer semifinalista en Copa Suramericana"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Independiente<\/strong> de Argentina se clasific\u00f3 a la final de la <strong>Copa Suramericana<\/strong> al vencer\u00a0 \u00a03-1 a <strong>Libertad<\/strong> de Paraguay, en el juego de vuelta por una de las semifinales disputado en el estadio Libertadores de Am\u00e9rica de Avellaneda.<u><\/u><u><\/u><\/p>\n<p style=\"text-align: justify;\"><strong>Ezequiel Barco<\/strong>, a los 17 minutos de penal y<strong> Emanuel Gigliotti<\/strong>, a los 18 y 31 minutos, marcaron los goles del triunfo, mientras que<strong> \u00c1ngel Cardozo<\/strong>, sobre los 24, descont\u00f3 para Libertad.<u><\/u><u><\/u><\/p>\n<p style=\"text-align: justify;\">Independiente, que ya fue campe\u00f3n del torneo en 2010, buscar\u00e1 su segundo trofeo en la final que disputar\u00e1 contra el vencedor de la serie entre <strong>Atl\u00e9tico Junior<\/strong> de Barranquilla y <strong>Flamengo<\/strong> de Rio de Janeiro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Independiente de Argentina se clasific\u00f3 a la final de la Copa Suramericana al vencer\u00a0 \u00a03-1 a Libertad de Paraguay, en el juego de vuelta por una de las semifinales disputado en el estadio Libertadores de Am\u00e9rica de Avellaneda. Ezequiel Barco, a los 17 minutos de penal y Emanuel Gigliotti, a los 18 y 31 minutos, [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":10306,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[152],"tags":[379,503,122],"class_list":{"0":"post-10301","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-mundo-futbol","8":"tag-copa-suramericana","9":"tag-independiente","10":"tag-libertad-de-paraguay"},"acf":[],"_links":{"self":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts\/10301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/comments?post=10301"}],"version-history":[{"count":1,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts\/10301\/revisions"}],"predecessor-version":[{"id":10312,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts\/10301\/revisions\/10312"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/media\/10306"}],"wp:attachment":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/media?parent=10301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/categories?post=10301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/tags?post=10301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}