{"id":107561,"date":"2024-04-22T14:02:29","date_gmt":"2024-04-22T19:02:29","guid":{"rendered":"https:\/\/futbolhoy.co\/?p=107561"},"modified":"2024-04-22T22:42:42","modified_gmt":"2024-04-23T03:42:42","slug":"zubeldia-hablo-de-james-rodriguez-lo-tendra-en-cuenta","status":"publish","type":"post","link":"https:\/\/futbolhoy.co\/index.php\/2024\/04\/22\/zubeldia-hablo-de-james-rodriguez-lo-tendra-en-cuenta\/","title":{"rendered":"Zubeld\u00eda habl\u00f3 de James Rodr\u00edguez: \u00bflo tendr\u00e1 en cuenta?"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif;\"><strong>S\u00e3o Paulo<\/strong> present\u00f3 este lunes a<strong> Luis Zubeld\u00eda<\/strong> como su nuevo entrenador, quien reemplazar\u00e1 en el cargo a <strong>Thiago Carpini.<\/strong> El argentino es el vigente t\u00e9cnico campe\u00f3n de la Copa Sudamericana luego de ganarla con Liga de Quito en 2023, pero se encontraba sin club desde inicios de enero.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif;\">Al entrenador de 43 a\u00f1os le preguntaron por sus sensaciones en su primer entrenamiento, as\u00ed como por <strong>James Rodr\u00edguez<\/strong>, el \u00fanico futbolista por el que le cuestionaron de manera puntual.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif;\">\u201cEs importante tener a todos los jugadores en el mejor nivel posible, ll\u00e1mese como se llame, cada jugador necesita una atenci\u00f3n particular de parte de nuestro grupo de trabajo, <strong>pero todos los jugadores tienen que pensar en funci\u00f3n del equipo, el equipo est\u00e1 por encima de cualquier nombre.<\/strong> Todos los seres humanos somos iguales, pero hay que hablar diferente con los jugadores y saber c\u00f3mo tocarle la tecla, esto tambi\u00e9n es por las culturas de donde vienen\u201d, dijo Zubeld\u00eda.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif;\">S\u00e3o Paulo inici\u00f3 con dos derrotas y un triunfo en los tres partidos disputados. James Rodr\u00edguez se perdi\u00f3 los \u00faltimos dos debido a una <strong>lesi\u00f3n muscular<\/strong> que lo tendr\u00e1 afuera de las canchas por las pr\u00f3ximas dos semanas.<\/span><\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"pt\" dir=\"ltr\">\ud83c\udf99\ufe0f Luis Zubeld\u00eda: \u201cN\u00e3o tive d\u00favidas em assumir, pela grandeza do clube e do elenco. Nos treinamentos vou poder ter um diagn\u00f3stico mais certeiro para preparar minha ideia de jogo. Mas conhe\u00e7o o grupo, nos enfrentamos e vejo muito o Brasileir\u00e3o. Estou contente, e mais importante \u00e9\u2026 <a href=\"https:\/\/t.co\/pH6869XXFA\">pic.twitter.com\/pH6869XXFA<\/a><\/p>\n<p>&mdash; S\u00e3o Paulo FC (@SaoPauloFC) <a href=\"https:\/\/twitter.com\/SaoPauloFC\/status\/1782471869800567028?ref_src=twsrc%5Etfw\">April 22, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00e3o Paulo present\u00f3 este lunes a Luis Zubeld\u00eda como su nuevo entrenador, quien reemplazar\u00e1 en el cargo a Thiago Carpini. El argentino es el vigente t\u00e9cnico campe\u00f3n de la Copa Sudamericana luego de ganarla con Liga de Quito en 2023, pero se encontraba sin club desde inicios de enero. Al entrenador de 43 a\u00f1os le [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":107562,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[152],"tags":[],"class_list":{"0":"post-107561","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-mundo-futbol"},"acf":[],"_links":{"self":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts\/107561","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/comments?post=107561"}],"version-history":[{"count":1,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts\/107561\/revisions"}],"predecessor-version":[{"id":107563,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts\/107561\/revisions\/107563"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/media\/107562"}],"wp:attachment":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/media?parent=107561"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/categories?post=107561"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/tags?post=107561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}