{"id":116243,"date":"2025-02-08T22:29:38","date_gmt":"2025-02-09T03:29:38","guid":{"rendered":"https:\/\/futbolhoy.co\/?p=116243"},"modified":"2025-02-09T22:29:37","modified_gmt":"2025-02-10T03:29:37","slug":"giordana-marca-gol-agonico-para-darle-el-triunfo-a-millonarios-ante-la-equidad","status":"publish","type":"post","link":"https:\/\/futbolhoy.co\/index.php\/2025\/02\/08\/giordana-marca-gol-agonico-para-darle-el-triunfo-a-millonarios-ante-la-equidad\/","title":{"rendered":"Giordana marca gol ag\u00f3nico para darle el triunfo a Millonarios ante La Equidad"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif;\"><strong>Millonarios<\/strong> consigui\u00f3 su segundo triunfo del semestre luego de vencer 2-1 a <strong>La Equidad<\/strong> en el estadio El Camp\u00edn. En el equipo Embajador, destac\u00f3 el regreso de Falcao, quien ingres\u00f3 en el segundo, al minuto 63, en reemplazo de <strong>Leonardo Castro.<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif;\">Apenas en 3 minutos de juego, el cuadro visitante se qued\u00f3 con uno menos por la expulsi\u00f3n de <strong>Guillermo Tegue<\/strong> por cometer falta contra Leonardo Castro como \u00faltimo hombre.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif;\">Al minuto 11 de partido, fall\u00f3 La Equidad en salida y el bal\u00f3n le qued\u00f3 a Castro, quien defini\u00f3 por debajo de las piernas del arquero <strong>Cristopher Varela<\/strong> para adelantar a los locales.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif;\">La igualdad lleg\u00f3 al 53\u2019. <strong>Beckham Castro<\/strong> centr\u00f3 desde la izquierda, durmi\u00f3 toda la defensa de Millonarios y en el segundo palo <strong>Renan Oliveira<\/strong> de cabeza la mand\u00f3 a guardar.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif;\">Con el ingreso de los delanteros, el que brill\u00f3 fue<strong> Santiago Giordana.<\/strong> Al minuto 80, centr\u00f3 desde la izquierda <strong>Danovis Banguero<\/strong> y el argentino se anticip\u00f3 para de cabeza convertir la anotaci\u00f3n del triunfo.<br \/>\n<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Millonarios consigui\u00f3 su segundo triunfo del semestre luego de vencer 2-1 a La Equidad en el estadio El Camp\u00edn. En el equipo Embajador, destac\u00f3 el regreso de Falcao, quien ingres\u00f3 en el segundo, al minuto 63, en reemplazo de Leonardo Castro. Apenas en 3 minutos de juego, el cuadro visitante se qued\u00f3 con uno menos [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":116244,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[7],"tags":[],"class_list":{"0":"post-116243","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-liga-betplay"},"acf":[],"_links":{"self":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts\/116243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/comments?post=116243"}],"version-history":[{"count":1,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts\/116243\/revisions"}],"predecessor-version":[{"id":116245,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts\/116243\/revisions\/116245"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/media\/116244"}],"wp:attachment":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/media?parent=116243"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/categories?post=116243"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/tags?post=116243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}