{"id":116431,"date":"2025-02-14T08:42:42","date_gmt":"2025-02-14T13:42:42","guid":{"rendered":"https:\/\/futbolhoy.co\/?p=116431"},"modified":"2025-02-15T18:18:11","modified_gmt":"2025-02-15T23:18:11","slug":"jugadoras-del-espanyol-muestran-su-apoyo-en-caso-daniela-caracas","status":"publish","type":"post","link":"https:\/\/futbolhoy.co\/index.php\/2025\/02\/14\/jugadoras-del-espanyol-muestran-su-apoyo-en-caso-daniela-caracas\/","title":{"rendered":"Jugadoras del Espanyol muestran su apoyo en caso Daniela Caracas"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif;\"><span style=\"font-weight: 400;\">Las jugadoras del Espanyol Femenino mostraron este viernes un mensaje de apoyo <\/span><b>a la colombiana Daniela Caracas<\/b><span style=\"font-weight: 400;\">, en medio de la pol\u00e9mica por el tocamiento que recibi\u00f3 por parte de la jugadora del Barcelona Mapi Le\u00f3n, durante el partido por la Liga del pasado domingo.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif;\"><span style=\"font-weight: 400;\">A trav\u00e9s de un <\/span><b>video publicado en las redes del club,<\/b><span style=\"font-weight: 400;\"> toda la plantilla insisti\u00f3 en condenar este lamentable hecho.\u00a0<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif;\"><span style=\"font-weight: 400;\">\u00abSobre todo, por el bien del f\u00fatbol femenino,<\/span><b> esperemos que esto no vuelva a suceder\u00bb,<\/b><span style=\"font-weight: 400;\"> dijo Carol Mar\u00edn, acompa\u00f1ada en las im\u00e1genes por Ainoa Campo, Lice Chamorro y Judit Pablos.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif;\"><span style=\"font-weight: 400;\">Las futbolistas del cuadro blanquiazul insistieron en su respaldo a la jugadora colombiana, que por el momento <\/span><b>no se ha pronunciado p\u00fablicamente tras lo sucedido.<\/b><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif;\"><span style=\"font-weight: 400;\">\u00abQueremos mostrar nuestro absoluto apoyo a nuestra compa\u00f1era Daniela Caracas, <\/span><b>que es una excelente profesional<\/b><span style=\"font-weight: 400;\">\u00ab, dijeron.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif;\"><span style=\"font-weight: 400;\">Las jugadoras tambi\u00e9n dejaron claro que est\u00e1n de acuerdo con la posici\u00f3n del club, que se public\u00f3 en un comunicado, en el que calific\u00f3 la situaci\u00f3n como \u00abinaceptable\u00bb al considerar que \u00abvulnera la intimidad\u00bb de Caracas. Misma situaci\u00f3n que Mapi Le\u00f3n <\/span><b>neg\u00f3 y que describi\u00f3 como \u00abun simple lance del juego\u00bb.<\/b><\/span><\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"es\">\ud83e\udec2 Mensaje de apoyo a Daniela Caracas<a href=\"https:\/\/twitter.com\/hashtag\/RCDE?src=hash&amp;ref_src=twsrc%5Etfw\">#RCDE<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/RCDEFem?src=hash&amp;ref_src=twsrc%5Etfw\">#RCDEFem<\/a> <a href=\"https:\/\/t.co\/2IVoIx0wUZ\">pic.twitter.com\/2IVoIx0wUZ<\/a><\/p>\n<p>\u2014 RCD Espanyol Femen\u00ed (@RCDEFemeni) <a href=\"https:\/\/twitter.com\/RCDEFemeni\/status\/1890364660286640556?ref_src=twsrc%5Etfw\">February 14, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las jugadoras del Espanyol Femenino mostraron este viernes un mensaje de apoyo a la colombiana Daniela Caracas, en medio de la pol\u00e9mica por el tocamiento que recibi\u00f3 por parte de la jugadora del Barcelona Mapi Le\u00f3n, durante el partido por la Liga del pasado domingo. A trav\u00e9s de un video publicado en las redes del [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":116432,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[418],"tags":[],"class_list":{"0":"post-116431","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-colombia"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jugadoras del Espanyol muestran su apoyo en caso Daniela Caracas -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/futbolhoy.co\/index.php\/2025\/02\/14\/jugadoras-del-espanyol-muestran-su-apoyo-en-caso-daniela-caracas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jugadoras del Espanyol muestran su apoyo en caso Daniela Caracas -\" \/>\n<meta property=\"og:description\" content=\"Las jugadoras del Espanyol Femenino mostraron este viernes un mensaje de apoyo a la colombiana Daniela Caracas, en medio de la pol\u00e9mica por el tocamiento que recibi\u00f3 por parte de la jugadora del Barcelona Mapi Le\u00f3n, durante el partido por la Liga del pasado domingo. A trav\u00e9s de un video publicado en las redes del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/futbolhoy.co\/index.php\/2025\/02\/14\/jugadoras-del-espanyol-muestran-su-apoyo-en-caso-daniela-caracas\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FutbolHoyCol\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-14T13:42:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-15T23:18:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/futbolhoy.co\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-14-a-las-8.41.50\u202fa.-m-1024x687.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"687\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"contenido\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FutbolHoyCol\" \/>\n<meta name=\"twitter:site\" content=\"@FutbolHoyCol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"contenido\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/futbolhoy.co\\\/index.php\\\/2025\\\/02\\\/14\\\/jugadoras-del-espanyol-muestran-su-apoyo-en-caso-daniela-caracas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/futbolhoy.co\\\/index.php\\\/2025\\\/02\\\/14\\\/jugadoras-del-espanyol-muestran-su-apoyo-en-caso-daniela-caracas\\\/\"},\"author\":{\"name\":\"contenido\",\"@id\":\"https:\\\/\\\/futbolhoy.co\\\/#\\\/schema\\\/person\\\/1721b69355b6623eaff15ac7b92d4cc3\"},\"headline\":\"Jugadoras del Espanyol muestran su apoyo en caso Daniela Caracas\",\"datePublished\":\"2025-02-14T13:42:42+00:00\",\"dateModified\":\"2025-02-15T23:18:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/futbolhoy.co\\\/index.php\\\/2025\\\/02\\\/14\\\/jugadoras-del-espanyol-muestran-su-apoyo-en-caso-daniela-caracas\\\/\"},\"wordCount\":230,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/futbolhoy.co\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/futbolhoy.co\\\/index.php\\\/2025\\\/02\\\/14\\\/jugadoras-del-espanyol-muestran-su-apoyo-en-caso-daniela-caracas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/futbolhoy.co\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Captura-de-pantalla-2025-02-14-a-las-8.41.50\u202fa.-m.png\",\"articleSection\":[\"Colombia\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/futbolhoy.co\\\/index.php\\\/2025\\\/02\\\/14\\\/jugadoras-del-espanyol-muestran-su-apoyo-en-caso-daniela-caracas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/futbolhoy.co\\\/index.php\\\/2025\\\/02\\\/14\\\/jugadoras-del-espanyol-muestran-su-apoyo-en-caso-daniela-caracas\\\/\",\"url\":\"https:\\\/\\\/futbolhoy.co\\\/index.php\\\/2025\\\/02\\\/14\\\/jugadoras-del-espanyol-muestran-su-apoyo-en-caso-daniela-caracas\\\/\",\"name\":\"Jugadoras del Espanyol muestran su apoyo en caso Daniela Caracas -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/futbolhoy.co\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/futbolhoy.co\\\/index.php\\\/2025\\\/02\\\/14\\\/jugadoras-del-espanyol-muestran-su-apoyo-en-caso-daniela-caracas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/futbolhoy.co\\\/index.php\\\/2025\\\/02\\\/14\\\/jugadoras-del-espanyol-muestran-su-apoyo-en-caso-daniela-caracas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/futbolhoy.co\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Captura-de-pantalla-2025-02-14-a-las-8.41.50\u202fa.-m.png\",\"datePublished\":\"2025-02-14T13:42:42+00:00\",\"dateModified\":\"2025-02-15T23:18:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/futbolhoy.co\\\/index.php\\\/2025\\\/02\\\/14\\\/jugadoras-del-espanyol-muestran-su-apoyo-en-caso-daniela-caracas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/futbolhoy.co\\\/index.php\\\/2025\\\/02\\\/14\\\/jugadoras-del-espanyol-muestran-su-apoyo-en-caso-daniela-caracas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/futbolhoy.co\\\/index.php\\\/2025\\\/02\\\/14\\\/jugadoras-del-espanyol-muestran-su-apoyo-en-caso-daniela-caracas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/futbolhoy.co\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Captura-de-pantalla-2025-02-14-a-las-8.41.50\u202fa.-m.png\",\"contentUrl\":\"https:\\\/\\\/futbolhoy.co\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Captura-de-pantalla-2025-02-14-a-las-8.41.50\u202fa.-m.png\",\"width\":1986,\"height\":1332},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/futbolhoy.co\\\/index.php\\\/2025\\\/02\\\/14\\\/jugadoras-del-espanyol-muestran-su-apoyo-en-caso-daniela-caracas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/futbolhoy.co\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jugadoras del Espanyol muestran su apoyo en caso Daniela Caracas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/futbolhoy.co\\\/#website\",\"url\":\"https:\\\/\\\/futbolhoy.co\\\/\",\"name\":\"FutbolHoy\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/futbolhoy.co\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/futbolhoy.co\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/futbolhoy.co\\\/#organization\",\"name\":\"Futbolhoy.co\",\"url\":\"https:\\\/\\\/futbolhoy.co\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/futbolhoy.co\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/futbolhoy.co\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/17426380_1906371736249227_6326180412931521141_n.jpg\",\"contentUrl\":\"https:\\\/\\\/futbolhoy.co\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/17426380_1906371736249227_6326180412931521141_n.jpg\",\"width\":960,\"height\":960,\"caption\":\"Futbolhoy.co\"},\"image\":{\"@id\":\"https:\\\/\\\/futbolhoy.co\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FutbolHoyCol\\\/\",\"https:\\\/\\\/x.com\\\/FutbolHoyCol\",\"https:\\\/\\\/www.instagram.com\\\/futbolhoycol\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/futbolhoy.co\\\/#\\\/schema\\\/person\\\/1721b69355b6623eaff15ac7b92d4cc3\",\"name\":\"contenido\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/599ff40a60b5c99b551a047057587d34c88fd496b4f5a2621cd66929dca918fe?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/599ff40a60b5c99b551a047057587d34c88fd496b4f5a2621cd66929dca918fe?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/599ff40a60b5c99b551a047057587d34c88fd496b4f5a2621cd66929dca918fe?s=96&d=mm&r=g\",\"caption\":\"contenido\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jugadoras del Espanyol muestran su apoyo en caso Daniela Caracas -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/futbolhoy.co\/index.php\/2025\/02\/14\/jugadoras-del-espanyol-muestran-su-apoyo-en-caso-daniela-caracas\/","og_locale":"es_ES","og_type":"article","og_title":"Jugadoras del Espanyol muestran su apoyo en caso Daniela Caracas -","og_description":"Las jugadoras del Espanyol Femenino mostraron este viernes un mensaje de apoyo a la colombiana Daniela Caracas, en medio de la pol\u00e9mica por el tocamiento que recibi\u00f3 por parte de la jugadora del Barcelona Mapi Le\u00f3n, durante el partido por la Liga del pasado domingo. A trav\u00e9s de un video publicado en las redes del [&hellip;]","og_url":"https:\/\/futbolhoy.co\/index.php\/2025\/02\/14\/jugadoras-del-espanyol-muestran-su-apoyo-en-caso-daniela-caracas\/","article_publisher":"https:\/\/www.facebook.com\/FutbolHoyCol\/","article_published_time":"2025-02-14T13:42:42+00:00","article_modified_time":"2025-02-15T23:18:11+00:00","og_image":[{"width":1024,"height":687,"url":"https:\/\/futbolhoy.co\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-14-a-las-8.41.50\u202fa.-m-1024x687.png","type":"image\/png"}],"author":"contenido","twitter_card":"summary_large_image","twitter_creator":"@FutbolHoyCol","twitter_site":"@FutbolHoyCol","twitter_misc":{"Escrito por":"contenido","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/futbolhoy.co\/index.php\/2025\/02\/14\/jugadoras-del-espanyol-muestran-su-apoyo-en-caso-daniela-caracas\/#article","isPartOf":{"@id":"https:\/\/futbolhoy.co\/index.php\/2025\/02\/14\/jugadoras-del-espanyol-muestran-su-apoyo-en-caso-daniela-caracas\/"},"author":{"name":"contenido","@id":"https:\/\/futbolhoy.co\/#\/schema\/person\/1721b69355b6623eaff15ac7b92d4cc3"},"headline":"Jugadoras del Espanyol muestran su apoyo en caso Daniela Caracas","datePublished":"2025-02-14T13:42:42+00:00","dateModified":"2025-02-15T23:18:11+00:00","mainEntityOfPage":{"@id":"https:\/\/futbolhoy.co\/index.php\/2025\/02\/14\/jugadoras-del-espanyol-muestran-su-apoyo-en-caso-daniela-caracas\/"},"wordCount":230,"commentCount":0,"publisher":{"@id":"https:\/\/futbolhoy.co\/#organization"},"image":{"@id":"https:\/\/futbolhoy.co\/index.php\/2025\/02\/14\/jugadoras-del-espanyol-muestran-su-apoyo-en-caso-daniela-caracas\/#primaryimage"},"thumbnailUrl":"https:\/\/futbolhoy.co\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-14-a-las-8.41.50\u202fa.-m.png","articleSection":["Colombia"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/futbolhoy.co\/index.php\/2025\/02\/14\/jugadoras-del-espanyol-muestran-su-apoyo-en-caso-daniela-caracas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/futbolhoy.co\/index.php\/2025\/02\/14\/jugadoras-del-espanyol-muestran-su-apoyo-en-caso-daniela-caracas\/","url":"https:\/\/futbolhoy.co\/index.php\/2025\/02\/14\/jugadoras-del-espanyol-muestran-su-apoyo-en-caso-daniela-caracas\/","name":"Jugadoras del Espanyol muestran su apoyo en caso Daniela Caracas -","isPartOf":{"@id":"https:\/\/futbolhoy.co\/#website"},"primaryImageOfPage":{"@id":"https:\/\/futbolhoy.co\/index.php\/2025\/02\/14\/jugadoras-del-espanyol-muestran-su-apoyo-en-caso-daniela-caracas\/#primaryimage"},"image":{"@id":"https:\/\/futbolhoy.co\/index.php\/2025\/02\/14\/jugadoras-del-espanyol-muestran-su-apoyo-en-caso-daniela-caracas\/#primaryimage"},"thumbnailUrl":"https:\/\/futbolhoy.co\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-14-a-las-8.41.50\u202fa.-m.png","datePublished":"2025-02-14T13:42:42+00:00","dateModified":"2025-02-15T23:18:11+00:00","breadcrumb":{"@id":"https:\/\/futbolhoy.co\/index.php\/2025\/02\/14\/jugadoras-del-espanyol-muestran-su-apoyo-en-caso-daniela-caracas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/futbolhoy.co\/index.php\/2025\/02\/14\/jugadoras-del-espanyol-muestran-su-apoyo-en-caso-daniela-caracas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/futbolhoy.co\/index.php\/2025\/02\/14\/jugadoras-del-espanyol-muestran-su-apoyo-en-caso-daniela-caracas\/#primaryimage","url":"https:\/\/futbolhoy.co\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-14-a-las-8.41.50\u202fa.-m.png","contentUrl":"https:\/\/futbolhoy.co\/wp-content\/uploads\/2025\/02\/Captura-de-pantalla-2025-02-14-a-las-8.41.50\u202fa.-m.png","width":1986,"height":1332},{"@type":"BreadcrumbList","@id":"https:\/\/futbolhoy.co\/index.php\/2025\/02\/14\/jugadoras-del-espanyol-muestran-su-apoyo-en-caso-daniela-caracas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/futbolhoy.co\/"},{"@type":"ListItem","position":2,"name":"Jugadoras del Espanyol muestran su apoyo en caso Daniela Caracas"}]},{"@type":"WebSite","@id":"https:\/\/futbolhoy.co\/#website","url":"https:\/\/futbolhoy.co\/","name":"FutbolHoy","description":"","publisher":{"@id":"https:\/\/futbolhoy.co\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/futbolhoy.co\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/futbolhoy.co\/#organization","name":"Futbolhoy.co","url":"https:\/\/futbolhoy.co\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/futbolhoy.co\/#\/schema\/logo\/image\/","url":"https:\/\/futbolhoy.co\/wp-content\/uploads\/2018\/08\/17426380_1906371736249227_6326180412931521141_n.jpg","contentUrl":"https:\/\/futbolhoy.co\/wp-content\/uploads\/2018\/08\/17426380_1906371736249227_6326180412931521141_n.jpg","width":960,"height":960,"caption":"Futbolhoy.co"},"image":{"@id":"https:\/\/futbolhoy.co\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FutbolHoyCol\/","https:\/\/x.com\/FutbolHoyCol","https:\/\/www.instagram.com\/futbolhoycol\/"]},{"@type":"Person","@id":"https:\/\/futbolhoy.co\/#\/schema\/person\/1721b69355b6623eaff15ac7b92d4cc3","name":"contenido","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/599ff40a60b5c99b551a047057587d34c88fd496b4f5a2621cd66929dca918fe?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/599ff40a60b5c99b551a047057587d34c88fd496b4f5a2621cd66929dca918fe?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/599ff40a60b5c99b551a047057587d34c88fd496b4f5a2621cd66929dca918fe?s=96&d=mm&r=g","caption":"contenido"}}]}},"_links":{"self":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts\/116431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/comments?post=116431"}],"version-history":[{"count":1,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts\/116431\/revisions"}],"predecessor-version":[{"id":116433,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts\/116431\/revisions\/116433"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/media\/116432"}],"wp:attachment":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/media?parent=116431"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/categories?post=116431"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/tags?post=116431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}