{"id":21258,"date":"2018-07-01T16:00:15","date_gmt":"2018-07-01T21:00:15","guid":{"rendered":"http:\/\/futbolhoy.co\/?p=21258"},"modified":"2018-07-01T20:09:02","modified_gmt":"2018-07-02T01:09:02","slug":"rusia-hace-historia-en-su-mundial-y-elimina-a-espana","status":"publish","type":"post","link":"https:\/\/futbolhoy.co\/index.php\/2018\/07\/01\/rusia-hace-historia-en-su-mundial-y-elimina-a-espana\/","title":{"rendered":"Rusia hace historia en su Mundial y elimina a Espa\u00f1a"},"content":{"rendered":"<p style=\"text-align: justify;\">La selecci\u00f3n de <strong>Rusia<\/strong> dio la gran sorpresa en los octavos de final de su <strong>Mundial<\/strong> y elimin\u00f3 a <strong>Espa\u00f1a<\/strong> en la v\u00eda desde el punto penal. La gran figura del compromiso fue el experimentado portero <strong>Akinf\u00e9ev<\/strong>, quien ataj\u00f3 dos ejecuciones desde los once pasos.<\/p>\n<p style=\"text-align: justify;\">Espa\u00f1a anot\u00f3 de manera tempranera tras 12 minutos de dominio sin respuesta del local, un cobro de tiro libre ib\u00e9rico golpe\u00f3 en el taco de <strong>Ignash\u00e9vich<\/strong>, quien dej\u00f3 sin respuesta al portero anfitri\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Sin embargo, con el marcador a favor los espa\u00f1oles fueron cediendo terreno y meti\u00e9ndose en su campo, por lo que en el cierre del primer tiempo Rusia encontr\u00f3 la igualdad tras una mano deliberada de <strong>Piqu\u00e9<\/strong> para cortar un cabezazo rival. El cobro lo cambi\u00f3 por gol <strong>Dzyuba<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Pese a que cont\u00f3 con el dominio de la pelota en la etapa complementaria, Espa\u00f1a no encontr\u00f3 una forma de romper la muralla defensiva rusa, menos a\u00fan de superar a Akinf\u00e9ev.<\/p>\n<p style=\"text-align: justify;\">Finalizados los 30 minutos de la pr\u00f3rroga, el portero del <strong>CSKA de Mosc\u00fa<\/strong> se consagr\u00f3 como figura al atajar las ejecuciones de <strong>Koke<\/strong> y el penal definitivo a <strong>Iago Aspas,<\/strong> el cual decret\u00f3 el triunfo 4-3 en la serie para los locales.<\/p>\n<p style=\"text-align: justify;\">Los anfitriones esperan rival en cuartos de final para el pr\u00f3ximo s\u00e1bado, el cual saldr\u00e1 del duelo entre <strong>Dinamarca<\/strong> y <strong>Croacia<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La selecci\u00f3n de Rusia dio la gran sorpresa en los octavos de final de su Mundial y elimin\u00f3 a Espa\u00f1a en la v\u00eda desde el punto penal. La gran figura del compromiso fue el experimentado portero Akinf\u00e9ev, quien ataj\u00f3 dos ejecuciones desde los once pasos. Espa\u00f1a anot\u00f3 de manera tempranera tras 12 minutos de dominio [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":21259,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[119,523,900],"class_list":{"0":"post-21258","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-mundial","9":"tag-seleccion-espana","10":"tag-seleccion-rusia"},"acf":[],"_links":{"self":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts\/21258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/comments?post=21258"}],"version-history":[{"count":3,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts\/21258\/revisions"}],"predecessor-version":[{"id":21263,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts\/21258\/revisions\/21263"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/media\/21259"}],"wp:attachment":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/media?parent=21258"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/categories?post=21258"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/tags?post=21258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}