{"id":23270,"date":"2018-08-07T17:50:05","date_gmt":"2018-08-07T22:50:05","guid":{"rendered":"http:\/\/futbolhoy.co\/?p=23270"},"modified":"2018-08-29T20:07:11","modified_gmt":"2018-08-30T01:07:11","slug":"gareca-renovara-con-peru-hasta-2022","status":"publish","type":"post","link":"https:\/\/futbolhoy.co\/index.php\/2018\/08\/07\/gareca-renovara-con-peru-hasta-2022\/","title":{"rendered":"Gareca renovar\u00e1 con Per\u00fa hasta 2022"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-size: medium; font-family: helvetica, arial, sans-serif;\">El t\u00e9cnico argentino\u00a0<b>Ricardo Gareca<\/b>\u00a0lleg\u00f3 a un acuerdo para renovar por cuatro a\u00f1os su v\u00ednculo con la selecci\u00f3n peruana y firmar\u00e1 su nuevo contrato el jueves, tras superar las diferencias con la Federaci\u00f3n.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium; font-family: helvetica, arial, sans-serif;\">\u00abLa firma del contrato de renovaci\u00f3n entre Ricardo Gareca y la\u00a0<b>Federaci\u00f3n Peruana de F\u00fatbol<\/b>\u00a0se dar\u00eda entre este mi\u00e9rcoles o este jueves\u00bb, se\u00f1al\u00f3 el diario El Comercio.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium; font-family: helvetica, arial, sans-serif;\">Las conversaciones se prolongaron m\u00e1s de una semana debido a que coincidieron con un esc\u00e1ndalo de audios de jueces, que salpic\u00f3 al presidente de la Federaci\u00f3n y desat\u00f3 una crisis interna en la entidad.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium; font-family: helvetica, arial, sans-serif;\">\u00abLos temas legales est\u00e1n claros y aceptados. El respaldo del directorio, la cl\u00e1usula de rescisi\u00f3n y la tranquilidad para el cuerpo t\u00e9cnico del estratega Ricardo Gareca, terminaron por convencer al hombre de leyes\u00bb, resalt\u00f3 diario.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium; font-family: helvetica, arial, sans-serif;\">Per\u00fa tiene como sus pr\u00f3ximos compromisos tres amistosos ante selecciones de gran poder,\u00a0<b>Holanda<\/b>\u00a0y\u00a0<b>Alemania<\/b>\u00a0en septiembre y\u00a0<b>Chile\u00a0<\/b>en octubre, adem\u00e1s de la\u00a0<b>Copa Am\u00e9rica-2019<\/b>\u00a0en\u00a0<b>Brasil\u00a0<\/b>y el inicio de las eliminatorias al\u00a0<b>Mundial de Qatar-2022<\/b>.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El t\u00e9cnico argentino\u00a0Ricardo Gareca\u00a0lleg\u00f3 a un acuerdo para renovar por cuatro a\u00f1os su v\u00ednculo con la selecci\u00f3n peruana y firmar\u00e1 su nuevo contrato el jueves, tras superar las diferencias con la Federaci\u00f3n. \u00abLa firma del contrato de renovaci\u00f3n entre Ricardo Gareca y la\u00a0Federaci\u00f3n Peruana de F\u00fatbol\u00a0se dar\u00eda entre este mi\u00e9rcoles o este jueves\u00bb, se\u00f1al\u00f3 el [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":23272,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[152],"tags":[186,446],"class_list":{"0":"post-23270","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-mundo-futbol","8":"tag-ricardo-gareca","9":"tag-seleccion-peru"},"acf":[],"_links":{"self":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts\/23270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/comments?post=23270"}],"version-history":[{"count":2,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts\/23270\/revisions"}],"predecessor-version":[{"id":23280,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts\/23270\/revisions\/23280"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/media\/23272"}],"wp:attachment":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/media?parent=23270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/categories?post=23270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/tags?post=23270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}