{"id":28089,"date":"2018-11-19T14:19:05","date_gmt":"2018-11-19T19:19:05","guid":{"rendered":"http:\/\/futbolhoy.co\/?p=28089"},"modified":"2018-11-21T21:20:11","modified_gmt":"2018-11-22T02:20:11","slug":"sabia-que-el-proceso-seria-tortuoso-rueda","status":"publish","type":"post","link":"https:\/\/futbolhoy.co\/index.php\/2018\/11\/19\/sabia-que-el-proceso-seria-tortuoso-rueda\/","title":{"rendered":"\u00abSab\u00eda que el proceso ser\u00eda tortuoso\u00bb, Rueda"},"content":{"rendered":"<div style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif;\">El seleccionador de Chile, el colombiano\u00a0<strong>Reinaldo Rueda<\/strong>, indic\u00f3 que <strong>Honduras<\/strong> ser\u00e1 un buen examen en el amistoso que sostendr\u00e1n este martes en\u00a0<strong>Temuco\u00a0<\/strong>luego de la derrota\u00a0sufrida ante\u00a0<strong>Costa Rica<\/strong>\u00a02-3 y se refiri\u00f3 a los silbidos de los que fue objeto por el desempe\u00f1o del equipo.<\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif;\">\u00a0<\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif;\">\u00abDesde el primer d\u00eda dije que ser\u00eda un proceso hasta cierto punto traum\u00e1tico, tortuoso, por todo lo que significa recuperar esa confianza en determinadas posiciones\u00bb, afirm\u00f3 <strong>Rueda<\/strong>, quien\u00a0consider\u00f3 que en el entorno de la selecci\u00f3n chilena se infravalor\u00f3 a un equipo mundialista como <strong>Costa Rica<\/strong> antes del partido del viernes y advirti\u00f3 de las virtudes de <strong>Honduras<\/strong>, selecci\u00f3n a la que dirigi\u00f3 en Sud\u00e1ffrica\u00a0en 2010.<\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif;\"><br \/>\n\u00abHonduras va a ser otra valoraci\u00f3n igual de dif\u00edcil, tiene jugadores explosivos y potentes. Debemos estar alerta y tener convicci\u00f3n. Hay que estar concentrados porque\u00a0Honduras\u00a0hace un juego muy vertical, muy directo. Es un buen examen para nosotros\u00bb, dijo Rueda en conferencia de prensa.<\/span><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El seleccionador de Chile, el colombiano\u00a0Reinaldo Rueda, indic\u00f3 que Honduras ser\u00e1 un buen examen en el amistoso que sostendr\u00e1n este martes en\u00a0Temuco\u00a0luego de la derrota\u00a0sufrida ante\u00a0Costa Rica\u00a02-3 y se refiri\u00f3 a los silbidos de los que fue objeto por el desempe\u00f1o del equipo. \u00a0 \u00abDesde el primer d\u00eda dije que ser\u00eda un proceso hasta cierto [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":28091,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[152],"tags":[96,288],"class_list":{"0":"post-28089","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-mundo-futbol","8":"tag-reinaldo-rueda","9":"tag-seleccion-chile"},"acf":[],"_links":{"self":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts\/28089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/comments?post=28089"}],"version-history":[{"count":1,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts\/28089\/revisions"}],"predecessor-version":[{"id":28094,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts\/28089\/revisions\/28094"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/media\/28091"}],"wp:attachment":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/media?parent=28089"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/categories?post=28089"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/tags?post=28089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}