{"id":29915,"date":"2019-01-07T06:43:29","date_gmt":"2019-01-07T11:43:29","guid":{"rendered":"http:\/\/futbolhoy.co\/?p=29915"},"modified":"2019-01-07T18:31:07","modified_gmt":"2019-01-07T23:31:07","slug":"james-el-colombiano-mas-valioso-del-mundo","status":"publish","type":"post","link":"https:\/\/futbolhoy.co\/index.php\/2019\/01\/07\/james-el-colombiano-mas-valioso-del-mundo\/","title":{"rendered":"James, el colombiano m\u00e1s valioso del mundo"},"content":{"rendered":"<p class=\"m_3860289723971669028ydpf869bbe0MsoNormal\" style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif;\">El volante <strong>James Rodr\u00edguez<\/strong>, del <strong>Bayern<\/strong> <strong>M\u00fanich<\/strong>, se mantiene como el colombiano m\u00e1s valioso del f\u00fatbol internacional en 2019.<\/span><\/p>\n<p class=\"m_3860289723971669028ydpf869bbe0MsoNormal\" style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif;\"><strong>Rodr\u00edguez<\/strong>, cuyos derechos deportivos pertenecen al <strong>Real Madrid<\/strong>, est\u00e1 valorado en 65 millones de euros, seguido por <strong>Davinson S\u00e1nchez<\/strong>, del <strong>Tottenham<\/strong>, cuyo costo asciende a 40 millones.<\/span><\/p>\n<p class=\"m_3860289723971669028ydpf869bbe0MsoNormal\" style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif;\">El rendimiento del <strong>M\u00f3naco<\/strong> ha afectado el costo de los derechos deportivos de <strong>Falcao Garc\u00eda<\/strong>, que est\u00e1 en 12 millones de euros.<\/span><\/p>\n<p class=\"m_3860289723971669028ydpf869bbe0MsoNormal\" style=\"text-align: justify;\">Top de los 10 colombianos m\u00e1s valiosos<\/p>\n<table>\n<tbody>\n<tr>\n<td>1. James Rodr\u00edguez (Bayern M\u00fanich)<\/td>\n<td>\u00a065 M\u20ac<\/td>\n<\/tr>\n<tr>\n<td>\u00a02. Davinson S\u00e1nchez (Tottenham)<\/td>\n<td>\u00a040 M\u20ac<\/td>\n<\/tr>\n<tr>\n<td>\u00a03. Yerry Mina (Everton)<\/td>\n<td>\u00a030 M\u20ac<\/td>\n<\/tr>\n<tr>\n<td>\u00a04. Juan Guillermo Cuadrado (Juventus)<\/td>\n<td>\u00a025 M\u20ac<\/td>\n<\/tr>\n<tr>\n<td>\u00a05. Jefferson Lerma (Bornemouth)<\/td>\n<td>\u00a025 M\u20ac<\/td>\n<\/tr>\n<tr>\n<td>\u00a06. Duv\u00e1n Zapata (Atalanta)<\/td>\n<td>\u00a022 M\u20ac<\/td>\n<\/tr>\n<tr>\n<td>\u00a07. Santiago Arias (Atl. De Madrid)<\/td>\n<td>\u00a020 M\u20ac<\/td>\n<\/tr>\n<tr>\n<td>\u00a08. Jeison Murillo (Barcelona)<\/td>\n<td>\u00a015 M\u20ac<\/td>\n<\/tr>\n<tr>\n<td>\u00a09. Jos\u00e9 Heriberto Izquierdo (Brigthon)<\/td>\n<td>\u00a013 M\u20ac<\/td>\n<\/tr>\n<tr>\n<td>\u00a010. Falcao Garc\u00eda (M\u00f3naco)<\/td>\n<td>\u00a012 M\u20ac<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>El volante James Rodr\u00edguez, del Bayern M\u00fanich, se mantiene como el colombiano m\u00e1s valioso del f\u00fatbol internacional en 2019. Rodr\u00edguez, cuyos derechos deportivos pertenecen al Real Madrid, est\u00e1 valorado en 65 millones de euros, seguido por Davinson S\u00e1nchez, del Tottenham, cuyo costo asciende a 40 millones. El rendimiento del M\u00f3naco ha afectado el costo de [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":29916,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[418],"tags":[87,165],"class_list":{"0":"post-29915","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-colombia","8":"tag-james-rodriguez","9":"tag-jugadores-colombianos"},"acf":[],"_links":{"self":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts\/29915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/comments?post=29915"}],"version-history":[{"count":4,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts\/29915\/revisions"}],"predecessor-version":[{"id":29920,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts\/29915\/revisions\/29920"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/media\/29916"}],"wp:attachment":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/media?parent=29915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/categories?post=29915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/tags?post=29915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}