{"id":53808,"date":"2020-07-25T11:33:57","date_gmt":"2020-07-25T16:33:57","guid":{"rendered":"https:\/\/futbolhoy.co\/?p=53808"},"modified":"2020-07-25T18:48:07","modified_gmt":"2020-07-25T23:48:07","slug":"maradona-critico-todo-y-a-todos","status":"publish","type":"post","link":"https:\/\/futbolhoy.co\/index.php\/2020\/07\/25\/maradona-critico-todo-y-a-todos\/","title":{"rendered":"Maradona critic\u00f3 todo y a todos"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif;\"><b>Diego Armando Maradona<\/b>\u00a0no dej\u00f3 t\u00edtere con cabeza y critic\u00f3 fuertemente al presidente de la\u00a0<b>FIFA<\/b>,\u00a0<b>Gianni Infantino<\/b>\u00a0y al ex mandatario argentino\u00a0<b>Mauricio Macri<\/b>, dentro de una reaparici\u00f3n p\u00fablica en televisi\u00f3n.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif;\">\u00abHabl\u00e9 una cosa con Infantino y me decepcion\u00f3. Yo veo que le dan un premio a Macri. \u00bfUn premio a qu\u00e9? Una patada en el culo hay que darle\u00bb, afirm\u00f3 Maradona en una entrevista con el canal de televisi\u00f3n\u00a0<i>C5N<\/i>.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif;\">\u201cTambi\u00e9n volvieron\u00a0<b>Michel Platini<\/b>\u00a0y\u00a0<b>Joseph Blatter<\/b>, las aguas se calmaron y se repartieron la plata entre ellos. Nadie devolvi\u00f3 nada. As\u00ed que yo renuncio a la FIFA\u201d, agreg\u00f3 el actual entrenador de\u00a0<b>Gimnasia y Esgrima La Plata<\/b>.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif;\">Con respecto a Macri, Maradona declar\u00f3: \u00abHay un mont\u00f3n de amigos suyos que se hicieron millonarios. Es simple, tiene que ir a la c\u00e1rcel con todos sus secuaces. En este pa\u00eds ya ten\u00edamos una pandemia y los argentinos sab\u00edamos que se nos ven\u00eda una pandemia de hambre. Macri se rob\u00f3 todo y no le dio un peso al nuevo estado nacional\u201d.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Diego Armando Maradona\u00a0no dej\u00f3 t\u00edtere con cabeza y critic\u00f3 fuertemente al presidente de la\u00a0FIFA,\u00a0Gianni Infantino\u00a0y al ex mandatario argentino\u00a0Mauricio Macri, dentro de una reaparici\u00f3n p\u00fablica en televisi\u00f3n. \u00abHabl\u00e9 una cosa con Infantino y me decepcion\u00f3. Yo veo que le dan un premio a Macri. \u00bfUn premio a qu\u00e9? Una patada en el culo hay que [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":53809,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[152],"tags":[],"class_list":{"0":"post-53808","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-mundo-futbol"},"acf":[],"_links":{"self":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts\/53808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/comments?post=53808"}],"version-history":[{"count":1,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts\/53808\/revisions"}],"predecessor-version":[{"id":53810,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts\/53808\/revisions\/53810"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/media\/53809"}],"wp:attachment":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/media?parent=53808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/categories?post=53808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/tags?post=53808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}