{"id":63953,"date":"2021-04-23T17:39:04","date_gmt":"2021-04-23T22:39:04","guid":{"rendered":"https:\/\/futbolhoy.co\/?p=63953"},"modified":"2021-04-24T08:26:57","modified_gmt":"2021-04-24T13:26:57","slug":"santos-firmo-alianza-con-nacional","status":"publish","type":"post","link":"https:\/\/futbolhoy.co\/index.php\/2021\/04\/23\/santos-firmo-alianza-con-nacional\/","title":{"rendered":"Santos firm\u00f3 alianza con Nacional"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif;\">El <strong>Santos Laguna<\/strong> de M\u00e9xico anunci\u00f3 que firm\u00f3 una alianza con los clubes, <strong>Betis<\/strong> de Espa\u00f1a, <strong>Atl\u00e9tico Nacional<\/strong> de Medell\u00edn y <strong>Banfield<\/strong> de Argentina, denominada \u2018Amor Verde y Blanco\u2019.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif;\">\u00abEstamos convencidos que Amor Verde y Blanco se convertir\u00e1 en una plataforma para impulsar la internacionalizaci\u00f3n de cada una de las instituciones, conscientes que tenemos un rol clave para fomentar el cari\u00f1o por estos colores y de esta forma llevar los valores que nos caracterizan a nuevas comunidades\u00bb, dice el comunicado del equipo azteca.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif;\">El presidente del equipo antioque\u00f1o,<strong> Juan David P\u00e9rez<\/strong>, asegur\u00f3 que este acuerdo representa una gran oportunidad para los diferentes equipos que lo componen.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif;\">\u201cUnir la pasi\u00f3n que compartimos por los colores y el f\u00fatbol nos permitir\u00e1n generar de esta, una alianza \u00fanica. Estamos emocionados de continuar con la internacionalizaci\u00f3n de la marca <strong>Atl\u00e9tico Nacional<\/strong> y hacerlo al lado de clubes con los cuales compartimos la pasi\u00f3n por los mismos colores. El f\u00fatbol es, definitivamente un lenguaje universal que nos acerca a todos\u201d, dijo el dirigente colombiano.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif;\">El acuerdo busca una cooperaci\u00f3n mutua que fortalezcan a las entidades deportivas.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Santos Laguna de M\u00e9xico anunci\u00f3 que firm\u00f3 una alianza con los clubes, Betis de Espa\u00f1a, Atl\u00e9tico Nacional de Medell\u00edn y Banfield de Argentina, denominada \u2018Amor Verde y Blanco\u2019. \u00abEstamos convencidos que Amor Verde y Blanco se convertir\u00e1 en una plataforma para impulsar la internacionalizaci\u00f3n de cada una de las instituciones, conscientes que tenemos un [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":63956,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[7],"tags":[147],"class_list":{"0":"post-63953","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-liga-betplay","8":"tag-nacional"},"acf":[],"_links":{"self":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts\/63953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/comments?post=63953"}],"version-history":[{"count":1,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts\/63953\/revisions"}],"predecessor-version":[{"id":63957,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts\/63953\/revisions\/63957"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/media\/63956"}],"wp:attachment":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/media?parent=63953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/categories?post=63953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/tags?post=63953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}