{"id":76332,"date":"2022-02-20T19:13:52","date_gmt":"2022-02-21T00:13:52","guid":{"rendered":"https:\/\/futbolhoy.co\/?p=76332"},"modified":"2022-02-21T17:10:04","modified_gmt":"2022-02-21T22:10:04","slug":"james-nego-pelea-con-falcao-y-tiene-fe-en-clasificar-al-mundial","status":"publish","type":"post","link":"https:\/\/futbolhoy.co\/index.php\/2022\/02\/20\/james-nego-pelea-con-falcao-y-tiene-fe-en-clasificar-al-mundial\/","title":{"rendered":"James neg\u00f3 pelea con Falcao y tiene fe en clasificar al Mundial"},"content":{"rendered":"<audio class=\"wp-audio-shortcode\" id=\"audio-76332-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/futbolhoy.co\/wp-content\/uploads\/2022\/02\/James-Rodriguez-en-Twitch..mp3?_=1\" \/><a href=\"https:\/\/futbolhoy.co\/wp-content\/uploads\/2022\/02\/James-Rodriguez-en-Twitch..mp3\">https:\/\/futbolhoy.co\/wp-content\/uploads\/2022\/02\/James-Rodriguez-en-Twitch..mp3<\/a><\/audio>\n<p style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif;\">(James Rodr\u00edguez en di\u00e1logo por su canal de Twitch).<br \/>\nEl volante cucute\u00f1o <strong>James Rodr\u00edguez<\/strong> neg\u00f3 las versiones surgidas en torno a una supuesta divisi\u00f3n de los jugadores al interior de la <strong>selecci\u00f3n Colombia<\/strong> y se mostr\u00f3 esperanzado en que el equipo lograr\u00e1 su clasificaci\u00f3n al <strong>Mundial Qatar-2022.<\/strong><\/span><\/p>\n<p>James tambi\u00e9n indic\u00f3 que se plantear\u00e1 en su momento la salida del Al <strong>Rayyan<\/strong> de Qatar, sin descartar regresar\u00a0a <strong>Europa<\/strong> o llegar a la <strong>MLS<\/strong> en <strong>Estados<\/strong> <strong>Unidos<\/strong> a corto plazo.<\/p>\n<p>El volante nacional, de 30 a\u00f1os, sostuvo una extensa charla con sus seguidores en su cuenta de <strong>Twitch<\/strong>, en la que tambi\u00e9n critic\u00f3 a los dirigentes del f\u00fatbol colombiano por tener poca planificaci\u00f3n a futuro.<\/p>\n<p>\u201cPelea con<b>\u00a0Falcao<\/b>, no, no, no, \u00bfC\u00f3mo voy a pensar con una persona que es mi hermano? Tenemos una relaci\u00f3n de 12 a\u00f1os, todo lo que se dice es mentira, no crean lo que dice la prensa. Dentro del grupo hay una excelente relaci\u00f3n entre todos, hay un buen ambiente, pero lastimosamente no se nos han dado los resultados, con Falcao y los otros muchas tengo una relaci\u00f3n fant\u00e1stica, no tengo ning\u00fan problema con nadie\u201d, declar\u00f3 James.<\/p>\n<p>Sobre la calidad del f\u00fatbol en Colombia indic\u00f3: \u201cPara que Colombia sea potencia los trabajos desde los directivos deben ser serios, proyectados a a\u00f1os que no sea a corto plazo, sino a\u00f1os, esos proyectos son serios y eso me gustar\u00eda aportar cuando ya no est\u00e9 jugando; cosas positivas dentro y fuera del campo\u201d.<\/p>\n<p>Respecto a la posibilidad de clasificar a la Copa del Mundo manifest\u00f3, \u201cHay fe para ir al Mundial, est\u00e1 duro, pero con los jugadores que tenemos se puede, hay que luchar hasta el final, tenemos que ganar los \u00faltimos partidos, tenemos un grupo de mucha calidad y hay con que, son cosas que no se pueden explicar, pero vamos a luchar hasta el final y hacer las cosas bien, el trabajo duro tiene su recompensa y darlo todo para tener la tranquilidad de que el trabajo est\u00e1 hecho\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(James Rodr\u00edguez en di\u00e1logo por su canal de Twitch). El volante cucute\u00f1o James Rodr\u00edguez neg\u00f3 las versiones surgidas en torno a una supuesta divisi\u00f3n de los jugadores al interior de la selecci\u00f3n Colombia y se mostr\u00f3 esperanzado en que el equipo lograr\u00e1 su clasificaci\u00f3n al Mundial Qatar-2022. James tambi\u00e9n indic\u00f3 que se plantear\u00e1 en su [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":71885,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":""},"categories":[418],"tags":[],"class_list":{"0":"post-76332","1":"post","2":"type-post","3":"status-publish","4":"format-video","5":"has-post-thumbnail","7":"category-colombia","8":"post_format-post-format-video"},"acf":[],"_links":{"self":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts\/76332","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/comments?post=76332"}],"version-history":[{"count":4,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts\/76332\/revisions"}],"predecessor-version":[{"id":76338,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts\/76332\/revisions\/76338"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/media\/71885"}],"wp:attachment":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/media?parent=76332"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/categories?post=76332"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/tags?post=76332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}