{"id":86823,"date":"2022-10-26T19:00:50","date_gmt":"2022-10-27T00:00:50","guid":{"rendered":"https:\/\/futbolhoy.co\/?p=86823"},"modified":"2022-10-28T08:57:01","modified_gmt":"2022-10-28T13:57:01","slug":"america-tampoco-alcanzo-la-final-de-la-libertadores","status":"publish","type":"post","link":"https:\/\/futbolhoy.co\/index.php\/2022\/10\/26\/america-tampoco-alcanzo-la-final-de-la-libertadores\/","title":{"rendered":"Am\u00e9rica tampoco alcanz\u00f3 la final de la Libertadores"},"content":{"rendered":"<div id=\"m#msg-f:1747795889147781477\" class=\"mail-message expanded\">\n<div class=\"mail-message-content collapsible zoom-normal mail-show-images \">\n<div class=\"clear\">\n<div>\n<div>\n<div dir=\"ltr\">\n<div>\n<p style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif;\"><b><span lang=\"ES-MX\">Colombia<\/span><\/b><span lang=\"ES-MX\">\u00a0no logr\u00f3 ubicar ninguno de sus equipos en la final de la\u00a0<b>Copa Libertadores Femenina de Ecuador<\/b>, luego de la derrota del\u00a0<b>Am\u00e9rica<\/b>\u00a01-0 ante\u00a0<b>Palmeiras<\/b>\u00a0en la segunda semifinal del torneo.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span lang=\"ES-MX\" style=\"font-family: helvetica, arial, sans-serif;\">El gol de las brasile\u00f1as lleg\u00f3 a los 55 minutos por intermedio de\u00a0<b>Ary Borges<\/b>\u00a0de golpe de cabeza.<\/span><\/p>\n<p style=\"text-align: justify;\"><span lang=\"ES-MX\" style=\"font-family: helvetica, arial, sans-serif;\">El arbitraje de la peruana\u00a0<b>Milagros Arruela<\/b>\u00a0fue muy cuestionado por el equipo colombiano, al dejar de sancionar una clara falta penalti en el segundo tiempo en favor de las dirigidas por\u00a0<b>Andr\u00e9s Usme<\/b>.<\/span><\/p>\n<p style=\"text-align: justify;\"><span lang=\"ES-MX\" style=\"font-family: helvetica, arial, sans-serif;\">El conjunto\u00a0<b>\u2018escarlata\u2019<\/b>\u00a0no logr\u00f3 meterse en la lucha por el t\u00edtulo y se sum\u00f3 al\u00a0<b>Deportivo Cali<\/b>\u00a0en la frustraci\u00f3n nacional por obtener el t\u00edtulo continental, que solo alcanz\u00f3 para el pa\u00eds el\u00a0<b>Atl\u00e9tico Huila<\/b>\u00a0en 2018.<\/span><\/p>\n<p style=\"text-align: justify;\"><span lang=\"ES-MX\" style=\"font-family: helvetica, arial, sans-serif;\">El campe\u00f3n colombiano ya hab\u00eda sido segundo en la\u00a0<b>Libertadores en 2020<\/b>.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif;\"><b><span lang=\"ES-MX\">El cl\u00e1sico vallecaucano<\/span><\/b><span lang=\"ES-MX\">\u00a0reeditar\u00e1 la final de la\u00a0<b>Liga colombiana<\/b>\u00a0en la lucha por el tercer lugar del evento continental este viernes a las 2 de la tarde; mientras que la final entre Palmeiras y\u00a0<b>Boca Juniors<\/b> se disputar\u00e1 a las 5PM el mismo d\u00eda.<\/span><\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Colombia\u00a0no logr\u00f3 ubicar ninguno de sus equipos en la final de la\u00a0Copa Libertadores Femenina de Ecuador, luego de la derrota del\u00a0Am\u00e9rica\u00a01-0 ante\u00a0Palmeiras\u00a0en la segunda semifinal del torneo. El gol de las brasile\u00f1as lleg\u00f3 a los 55 minutos por intermedio de\u00a0Ary Borges\u00a0de golpe de cabeza. El arbitraje de la peruana\u00a0Milagros Arruela\u00a0fue muy cuestionado por el equipo [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":86824,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[653],"tags":[],"class_list":{"0":"post-86823","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-copa-libertadores"},"acf":[],"_links":{"self":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts\/86823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/comments?post=86823"}],"version-history":[{"count":2,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts\/86823\/revisions"}],"predecessor-version":[{"id":86840,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts\/86823\/revisions\/86840"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/media\/86824"}],"wp:attachment":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/media?parent=86823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/categories?post=86823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/tags?post=86823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}