{"id":87565,"date":"2022-11-21T09:26:18","date_gmt":"2022-11-21T14:26:18","guid":{"rendered":"https:\/\/futbolhoy.co\/?p=87565"},"modified":"2022-11-22T07:34:47","modified_gmt":"2022-11-22T12:34:47","slug":"luto-en-el-tolima-fallecio-su-maximo-accionista","status":"publish","type":"post","link":"https:\/\/futbolhoy.co\/index.php\/2022\/11\/21\/luto-en-el-tolima-fallecio-su-maximo-accionista\/","title":{"rendered":"Luto en el Tolima. Falleci\u00f3 su m\u00e1ximo accionista"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif;\">El dirigente deportivo boyacense, <strong>Gabriel Camargo Salamanca,<\/strong> m\u00e1ximo accionista del D<strong>eportes Tolima,<\/strong> falleci\u00f3 este lunes en <strong>Bogot\u00e1.<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif;\">\u201cTras una larga y dif\u00edcil batalla contra el c\u00e1ncer, en la madrugada de este lunes, en la ciudad de Bogot\u00e1, falleci\u00f3 Don Gabriel Camargo Salamanca, m\u00e1ximo accionista del Club Deportes Tolima, quien por m\u00e1s de 43 a\u00f1os lider\u00f3 nuestra instituci\u00f3n\u201d, inform\u00f3 el equipo.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif;\">Camargo, quien lleg\u00f3 al club a finales de los a\u00f1os 70 junto a Eduardo Robayo, tuvo un paso por cargos p\u00fablicos donde fue concejal de <strong>Fusagasug\u00e1,<\/strong> diputado de l<strong>a Asamblea de Cundinamarca<\/strong> y senador de la <strong>Rep\u00fablica.<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif;\">Don Gabriel, de 80 a\u00f1os y nacido en <strong>Tunja,<\/strong> se alej\u00f3 del club durante los a\u00f1os 80s y retom\u00f3 su liderazgo a medidos de la siguiente d\u00e9cada, donde se perdi\u00f3 la categor\u00eda y estuvo una temporada en la <strong>Primera B<\/strong> del f\u00fatbol colombiano.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif;\">El directivo fue art\u00edfice de los<strong> tres t\u00edtulos en primera divisi\u00f3n (2003-II, 2018-I, 2021-I). Adem\u00e1s, la Copa Colombia de 2014 y la Superliga de este a\u00f1o.<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif;\">Las exequias de Camargo se cumplir\u00e1n este mi\u00e9rcoles (11.30am) en la <strong>Capilla del Gimnasio Moderno de Bogot\u00e1.<\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El dirigente deportivo boyacense, Gabriel Camargo Salamanca, m\u00e1ximo accionista del Deportes Tolima, falleci\u00f3 este lunes en Bogot\u00e1. \u201cTras una larga y dif\u00edcil batalla contra el c\u00e1ncer, en la madrugada de este lunes, en la ciudad de Bogot\u00e1, falleci\u00f3 Don Gabriel Camargo Salamanca, m\u00e1ximo accionista del Club Deportes Tolima, quien por m\u00e1s de 43 a\u00f1os lider\u00f3 [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":87566,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[7],"tags":[],"class_list":{"0":"post-87565","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-liga-betplay"},"acf":[],"_links":{"self":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts\/87565","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/comments?post=87565"}],"version-history":[{"count":1,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts\/87565\/revisions"}],"predecessor-version":[{"id":87567,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts\/87565\/revisions\/87567"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/media\/87566"}],"wp:attachment":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/media?parent=87565"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/categories?post=87565"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/tags?post=87565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}