{"id":96365,"date":"2023-06-15T20:45:57","date_gmt":"2023-06-16T01:45:57","guid":{"rendered":"https:\/\/futbolhoy.co\/?p=96365"},"modified":"2023-06-16T11:54:26","modified_gmt":"2023-06-16T16:54:26","slug":"bacca-tiene-una-lesion-irreversible-de-rodilla-medico-de-junior","status":"publish","type":"post","link":"https:\/\/futbolhoy.co\/index.php\/2023\/06\/15\/bacca-tiene-una-lesion-irreversible-de-rodilla-medico-de-junior\/","title":{"rendered":"Bacca tiene una lesi\u00f3n irreversible de rodilla: m\u00e9dico de Junior"},"content":{"rendered":"<p class=\"ydp5a699179MsoNormal\" style=\"text-align: justify;\"><span lang=\"ES-MX\" style=\"font-family: helvetica, arial, sans-serif;\">La permanencia del delantero <strong>Carlos Bacca<\/strong> en <strong>Junior<\/strong> qued\u00f3 comprometida, luego que el m\u00e9dico del club, <strong>Javier Fern\u00e1ndez<\/strong>, revel\u00f3 que tiene una lesi\u00f3n en una de sus rodillas.<\/span><\/p>\n<p class=\"ydp5a699179MsoNormal\" style=\"text-align: justify;\"><span lang=\"ES-MX\" style=\"font-family: helvetica, arial, sans-serif;\">\u201cEl tema de <strong>Carlos (Bacca)<\/strong> es un tema delicado porque tiene un inconveniente en una de sus rodillas. Queremos que sea un Bacca que todos hemos visto, pero hay inconvenientes. \u00c9l quiere seguir entrenando para el alto nivel, pero tenemos que conversar, pensar y procesar la informaci\u00f3n que tenemos acerca de Carlos\u201d, sostuvo Fern\u00e1ndez.<\/span><\/p>\n<p class=\"ydp5a699179MsoNormal\" style=\"text-align: justify;\"><span lang=\"ES-MX\" style=\"font-family: helvetica, arial, sans-serif;\">\u201cBacca tiene una lesi\u00f3n irreversible en su rodilla derecha. Este problema lo limita en muchas cosas como saltar y correr, y la capacidad de reacci\u00f3n la pierde con este problema. Vamos a conversar esto con el profesor <strong>Hern\u00e1n (Dar\u00edo G\u00f3mez), Don Fuad (Char) y con Carlos (Bacca)\u201d<\/strong>, agreg\u00f3.<\/span><\/p>\n<p class=\"ydp5a699179MsoNormal\" style=\"text-align: justify;\"><span lang=\"ES-MX\" style=\"font-family: helvetica, arial, sans-serif;\">En las \u00faltimas horas, \u2018Bolillo\u2019 G\u00f3mez hab\u00eda dejado en suspenso la permanencia del jugador por situaciones que no revel\u00f3.<\/span><\/p>\n<p class=\"ydp5a699179MsoNormal\" style=\"text-align: justify;\"><span lang=\"ES-MX\" style=\"font-family: helvetica, arial, sans-serif;\">\u201cSiempre he querido a Carlos Bacca desde pelado, por su capacidad, sus triunfos que ha tenido, su historia grande. Es una persona que ha hecho mucho por el Junior. Ac\u00e1 est\u00e1 Carlos trabajando duro, es una situaci\u00f3n que todav\u00eda no hemos resuelto, es un jugador que todo el mundo lo quiere, yo lo quiero\u201d, coment\u00f3.<\/span><\/p>\n<p class=\"ydp5a699179MsoNormal\" style=\"text-align: justify;\"><span lang=\"ES-MX\" style=\"font-family: helvetica, arial, sans-serif;\">El jugador, nacido en <strong>Puerto Colombia<\/strong>, tiene contrato vigente con Junior hasta diciembre de 2024.<\/span><\/p>\n<p class=\"ydp5a699179MsoNormal\" style=\"text-align: justify;\"><span lang=\"ES-MX\" style=\"font-family: helvetica, arial, sans-serif;\">Una decisi\u00f3n sobre la continuidad de Bacca se tomar\u00e1 en los pr\u00f3ximos d\u00edas, buscando lo mejor para el equipo y el delantero.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La permanencia del delantero Carlos Bacca en Junior qued\u00f3 comprometida, luego que el m\u00e9dico del club, Javier Fern\u00e1ndez, revel\u00f3 que tiene una lesi\u00f3n en una de sus rodillas. \u201cEl tema de Carlos (Bacca) es un tema delicado porque tiene un inconveniente en una de sus rodillas. Queremos que sea un Bacca que todos hemos visto, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":96366,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[7],"tags":[],"class_list":{"0":"post-96365","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-liga-betplay"},"acf":[],"_links":{"self":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts\/96365","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/comments?post=96365"}],"version-history":[{"count":1,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts\/96365\/revisions"}],"predecessor-version":[{"id":96367,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts\/96365\/revisions\/96367"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/media\/96366"}],"wp:attachment":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/media?parent=96365"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/categories?post=96365"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/tags?post=96365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}