{"id":96626,"date":"2023-06-26T16:31:39","date_gmt":"2023-06-26T21:31:39","guid":{"rendered":"https:\/\/futbolhoy.co\/?p=96626"},"modified":"2023-06-27T15:50:19","modified_gmt":"2023-06-27T20:50:19","slug":"falcao-es-viable-en-millonarios-serpa","status":"publish","type":"post","link":"https:\/\/futbolhoy.co\/index.php\/2023\/06\/26\/falcao-es-viable-en-millonarios-serpa\/","title":{"rendered":"Falcao es viable en Millonarios: Serpa"},"content":{"rendered":"<p class=\"x_ydp6f8b6922MsoNormal\" style=\"text-align: justify;\"><span lang=\"ES-MX\" style=\"font-family: helvetica, arial, sans-serif;\">El campe\u00f3n <strong>Millonarios<\/strong> no ha descartado la idea y considera viable la posibilidad de contratar en un futuro cercano al goleador <strong>Falcao Garc\u00eda,<\/strong> asegur\u00f3 el presidente de la junta directiva del club <strong>Gustavo Serpa.<\/strong><\/span><\/p>\n<p class=\"x_ydp6f8b6922MsoNormal\" style=\"text-align: justify;\"><span lang=\"ES-MX\" style=\"font-family: helvetica, arial, sans-serif;\">\u201cHe tratado de reunirme con Falcao en los \u00faltimos meses, pero no se ha podido por el cruce de agendas, pero voy a tratar de hacerlo en julio cuando vaya a <strong>Madrid<\/strong> (\u2026) Yo creo que es viable desde el punto de vista econ\u00f3mico porque tendr\u00edamos el inter\u00e9s de hacerlo\u201d, sostuvo Serpa.<\/span><\/p>\n<p class=\"x_ydp6f8b6922MsoNormal\" style=\"text-align: justify;\"><span lang=\"ES-MX\" style=\"font-family: helvetica, arial, sans-serif;\">\u201cMi percepci\u00f3n es que Falcao tiene un tema personal y familiar. \u00c9l est\u00e1 c\u00f3modo en Madrid y mover a su familia en estos momentos de Madrid a Bogot\u00e1, despu\u00e9s de vivir tantos a\u00f1os en Europa, no es f\u00e1cil (\u2026) Lo voy a intentar. Es un viejo anhelo de la hinchada y nosotros nos debemos a ella\u201d, agreg\u00f3 Serpa en <strong><em>El VBar<\/em><\/strong> de <strong>Caracol Radio.<\/strong> \u00a0<\/span><\/p>\n<p class=\"x_ydp6f8b6922MsoNormal\" style=\"text-align: justify;\"><span lang=\"ES-MX\" style=\"font-family: helvetica, arial, sans-serif;\">\u201cNo soy optimista, pero creo que lo podr\u00edamos lograr. Soy propositivo en la medida en que quisiera lograrlo; imag\u00ednese que nos acompa\u00f1ara Falcao en el pr\u00f3ximo semestre. Es un sue\u00f1o que tenemos todos, pero b\u00e1sicamente depender\u00e1 de \u00e9l\u201d, puntualiz\u00f3 sobre el tema.<\/span><\/p>\n<p class=\"x_ydp6f8b6922MsoNormal\" style=\"text-align: justify;\"><span lang=\"ES-MX\" style=\"font-family: helvetica, arial, sans-serif;\">El goleador est\u00e1 finalizado su contrato con <strong>Rayo Vallecano,<\/strong> pero el equipo espa\u00f1ol estar\u00eda interesado en ampliar su v\u00ednculo por un a\u00f1o m\u00e1s.<\/span><\/p>\n<p class=\"x_ydp6f8b6922MsoNormal\" style=\"text-align: justify;\"><span lang=\"ES-MX\" style=\"font-family: helvetica, arial, sans-serif;\">El dirigente tambi\u00e9n adelant\u00f3 que el club gestiona las licencias para la construcci\u00f3n de un centro de alto rendimiento, en los terrenos que posee al norte de <strong>Bogot\u00e1.<\/strong> El prop\u00f3sito es contar con esa sede un tiempo m\u00e1ximo de 8 meses.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El campe\u00f3n Millonarios no ha descartado la idea y considera viable la posibilidad de contratar en un futuro cercano al goleador Falcao Garc\u00eda, asegur\u00f3 el presidente de la junta directiva del club Gustavo Serpa. \u201cHe tratado de reunirme con Falcao en los \u00faltimos meses, pero no se ha podido por el cruce de agendas, pero [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":72152,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[7],"tags":[],"class_list":{"0":"post-96626","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-liga-betplay"},"acf":[],"_links":{"self":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts\/96626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/comments?post=96626"}],"version-history":[{"count":1,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts\/96626\/revisions"}],"predecessor-version":[{"id":96627,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/posts\/96626\/revisions\/96627"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/media\/72152"}],"wp:attachment":[{"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/media?parent=96626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/categories?post=96626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/futbolhoy.co\/index.php\/wp-json\/wp\/v2\/tags?post=96626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}